{"id":328459,"date":"2023-12-01T16:11:17","date_gmt":"2023-12-01T15:11:17","guid":{"rendered":"https:\/\/www.parispackagingweek.com\/?post_type=activity&#038;p=328459"},"modified":"2024-01-16T14:54:26","modified_gmt":"2024-01-16T13:54:26","slug":"e-commerce-de-luxe-lengagement-client-a-travers-le-packagingaspect-de-la-logistique-jusquau-deballage-du-produit","status":"publish","type":"activity","link":"https:\/\/www.parispackagingweek.com\/fr\/session\/e-commerce-de-luxe-lengagement-client-a-travers-le-packagingaspect-de-la-logistique-jusquau-deballage-du-produit\/","title":{"rendered":"L&rsquo;engagement client \u00e0 l&rsquo;heure de la durabilit\u00e9 dans le retail de luxe"},"content":{"rendered":"\n<p>Mod\u00e9ratrice: Claire Domergue, R\u00e9dactrice en chef, Luxus Plus <br>Nicolas Martin, Sustainable Store Planning Manager, LVMH<br>Jeremy Alonso, Head of Eco Innovation &#8211; GUERLAIN &#8211; LVMH<br>Emeric Crepin, Managing France, Arvato<br><\/p>\n\n\n\n<p>Les clients de luxe souhaitent des produits cr\u00e9atifs, durables et respectueux de l\u2019environnement. Mais c&rsquo;est tout le&nbsp;parcours d\u2019achat qui doit r\u00e9pondre \u00e0 ce besoin, depuis l&rsquo;arriv\u00e9e en boutique, jusqu&rsquo;au produit, en passant par le packaging. Cette forte attraction pour la durabilit\u00e9 \u00e9cologique s\u2019exprime \u00e9galement dans le souhait des consommateurs du luxe de b\u00e9n\u00e9ficier d&rsquo;une exp\u00e9rience de qualit\u00e9 sup\u00e9rieure, l\u2019un des piliers fondamentaux du luxe.<\/p>\n\n\n\n<p>Les g\u00e9ants mondiaux du luxe ont ainsi adopt\u00e9 une strat\u00e9gie ambitieuse de d\u00e9veloppement durable qui&nbsp;se v\u00e9rifie sur tous les points de contact (merchandising, mat\u00e9riaux d&#8217;emballage, \u00e9clairage, transport, logistique,..). En engageant leurs marques dans la lutte contre le changement climatique, les leaders du luxe r\u00e9pondent ainsi aux demandes \u00e9mergentes de leurs clients.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mod\u00e9ratrice: Claire Domergue, R\u00e9dactrice en chef, Luxus Plus Nicolas Martin, Sustainable Store Planning Manager, LVMHJeremy Alonso, Head of Eco Innovation &#8211; GUERLAIN &#8211; LVMHEmeric Crepin, Managing France, Arvato Les clients de luxe souhaitent des produits cr\u00e9atifs, durables et respectueux de l\u2019environnement. Mais c&rsquo;est tout le&nbsp;parcours d\u2019achat qui doit r\u00e9pondre \u00e0 ce besoin, depuis l&rsquo;arriv\u00e9e en [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_seopress_titles_title":"Circular Economy Stage | Zoe Truchy, Mondi Group","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"Circular Economy Stage | Zoe Truchy, Mondi Group","_seopress_social_fb_desc":"Zoe Truchy investit sa passion de longue date pour le papier dans la gamme de papiers premium de Mondi, PERGRAPHICA\u00ae. Elle adore accompagner ces magnifiques papiers dans un voyage cr\u00e9atif, en admirant les feuilles vierges se transformer en d&#039;\u00e9tonnants projets de design cr\u00e9atif, d&#039;\u00e9dition haut de gamme et de packaging de luxe. D&#039;origine britannique, sa carri\u00e8re dans le marketing et la communication l&#039;a men\u00e9e \u00e0 travers l&#039;Europe dans diff\u00e9rentes fonctions, d\u00e9veloppant ainsi son attachement au papier, \u00e0 l&#039;emballage de luxe, \u00e0 la papeterie et aux livres. Elle a pass\u00e9 17 ans dans le marketing et la communication en France, avant de rejoindre l&#039;\u00e9quipe de Mondi \u00e0 Vienne, en Autriche, en 2019.","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"Circular Economy Stage | Zoe Truchy, Mondi Group","_seopress_social_twitter_desc":"Zoe Truchy investit sa passion de longue date pour le papier dans la gamme de papiers premium de Mondi, PERGRAPHICA\u00ae. Elle adore accompagner ces magnifiques papiers dans un voyage cr\u00e9atif, en admirant les feuilles vierges se transformer en d&#039;\u00e9tonnants projets de design cr\u00e9atif, d&#039;\u00e9dition haut de gamme et de packaging de luxe. D&#039;origine britannique, sa carri\u00e8re dans le marketing et la communication l&#039;a men\u00e9e \u00e0 travers l&#039;Europe dans diff\u00e9rentes fonctions, d\u00e9veloppant ainsi son attachement au papier, \u00e0 l&#039;emballage de luxe, \u00e0 la papeterie et aux livres. Elle a pass\u00e9 17 ans dans le marketing et la communication en France, avant de rejoindre l&#039;\u00e9quipe de Mondi \u00e0 Vienne, en Autriche, en 2019.","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_activity_time_start":"14:15","_activity_time_end":"15:00","_activity_date":"2024-01-18","_activity_price":"0","footnotes":""},"edition":[744],"location":[775],"track":[],"activity_type":[],"class_list":["post-328459","activity","type-activity","status-publish","hentry","edition-paris-packaging-week-speakers-2024","location-future-innovation-forum-2024"],"_guests":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/331034"},{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/331013"},{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/330995"}],"_sponsors":[],"_cover_image":null,"_links":{"self":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/activity\/328459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/activity"}],"about":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/types\/activity"}],"version-history":[{"count":0,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/activity\/328459\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media?parent=328459"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/edition?post=328459"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/location?post=328459"},{"taxonomy":"track","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/track?post=328459"},{"taxonomy":"activity_type","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/activity_type?post=328459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}