{"id":328258,"date":"2023-12-01T13:00:31","date_gmt":"2023-12-01T12:00:31","guid":{"rendered":"https:\/\/www.parispackagingweek.com\/?post_type=guest&#038;p=328258"},"modified":"2023-12-20T18:28:13","modified_gmt":"2023-12-20T17:28:13","slug":"isabelle-le-graet","status":"publish","type":"guest","link":"https:\/\/www.parispackagingweek.com\/fr\/speaker\/isabelle-le-graet\/","title":{"rendered":"Isabelle Le Gra\u00ebt"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":334026,"template":"","meta":{"_seopress_titles_title":"Circular Economy Stage | Isabelle Le Gra\u00ebt, Eviosys","_seopress_titles_desc":" Isabelle Le Gra\u00ebt est responsable du marketing, de la communication et du d\u00e9veloppement durable chez Eviosys, leader dans la fabrication d&#039;emballages m\u00e9talliques. Fervente d\u00e9fenseuse des mat\u00e9riaux permanents, Isabelle apporte plus de 10 ans d&#039;expertise dans l&#039;industrie de l&#039;emballage, avec de l&#039;exp\u00e9rience dans le recyclage des emballages en plastique, en verre et en m\u00e9tal. Elle est titulaire d&#039;une ma\u00eetrise en strat\u00e9gie marketing et d&#039;un certificat en emballage durable dans une \u00e9conomie circulaire de l&#039;Universit\u00e9 technique de Delft.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"Circular Economy Stage | Isabelle Le Gra\u00ebt, Eviosys","_seopress_social_fb_desc":" Isabelle Le Gra\u00ebt est responsable du marketing, de la communication et du d\u00e9veloppement durable chez Eviosys, leader dans la fabrication d&#039;emballages m\u00e9talliques. Fervente d\u00e9fenseuse des mat\u00e9riaux permanents, Isabelle apporte plus de 10 ans d&#039;expertise dans l&#039;industrie de l&#039;emballage, avec de l&#039;exp\u00e9rience dans le recyclage des emballages en plastique, en verre et en m\u00e9tal. Elle est titulaire d&#039;une ma\u00eetrise en strat\u00e9gie marketing et d&#039;un certificat en emballage durable dans une \u00e9conomie circulaire de l&#039;Universit\u00e9 technique de Delft.","_seopress_social_fb_img":"https:\/\/easyfairsassets.com\/sites\/61\/2023\/12\/isabelle.png","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"Circular Economy Stage | Isabelle Le Gra\u00ebt, Eviosys","_seopress_social_twitter_desc":" Isabelle Le Gra\u00ebt est responsable du marketing, de la communication et du d\u00e9veloppement durable chez Eviosys, leader dans la fabrication d&#039;emballages m\u00e9talliques. Fervente d\u00e9fenseuse des mat\u00e9riaux permanents, Isabelle apporte plus de 10 ans d&#039;expertise dans l&#039;industrie de l&#039;emballage, avec de l&#039;exp\u00e9rience dans le recyclage des emballages en plastique, en verre et en m\u00e9tal. Elle est titulaire d&#039;une ma\u00eetrise en strat\u00e9gie marketing et d&#039;un certificat en emballage durable dans une \u00e9conomie circulaire de l&#039;Universit\u00e9 technique de Delft.","_seopress_social_twitter_img":"https:\/\/easyfairsassets.com\/sites\/61\/2023\/12\/isabelle.png","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_company_name":"Eviosys","_job_title":"Marketing, Communication and Sustainability Manager","_visit_me":"","_email":"","_linkedin":"","_twitter":"","_facebook":"","_instagram":"","_youtube":"","_imdb":"","footnotes":""},"edition":[744],"guest_type":[769],"work":[],"class_list":["post-328258","guest","type-guest","status-publish","has-post-thumbnail","hentry","edition-paris-packaging-week-speakers-2024","guest_type-circular-economy-stage"],"_cover_image":null,"_links":{"self":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/328258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest"}],"about":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/types\/guest"}],"version-history":[{"count":0,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/328258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media\/334026"}],"wp:attachment":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media?parent=328258"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/edition?post=328258"},{"taxonomy":"guest_type","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest_type?post=328258"},{"taxonomy":"work","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/work?post=328258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}