{"id":417255,"date":"2024-12-04T17:56:37","date_gmt":"2024-12-04T16:56:37","guid":{"rendered":"https:\/\/www.parispackagingweek.com\/?post_type=guest&#038;p=417255"},"modified":"2024-12-04T17:57:35","modified_gmt":"2024-12-04T16:57:35","slug":"luc-hillege","status":"publish","type":"guest","link":"https:\/\/www.parispackagingweek.com\/fr\/speaker\/luc-hillege\/","title":{"rendered":"Luc Hillege"},"content":{"rendered":"\n<p>Luc est un sp\u00e9cialiste et un d\u00e9fenseur de l&rsquo;environnement passionn\u00e9 par le d\u00e9veloppement durable et l&rsquo;expression cr\u00e9ative. Combinant son expertise en mati\u00e8re d&rsquo;analyse du cycle de vie (ACV) et sa profonde compr\u00e9hension du d\u00e9veloppement durable, il applique ces connaissances \u00e0 l&rsquo;industrie des a\u00e9rosols et de la peinture en a\u00e9rosol. En tant que fondateur de l&rsquo;Aerosol Alliance, Luc travaille avec des artistes, des conservateurs, des fabricants et des recycleurs pour sensibiliser le public et trouver des solutions durables.<\/p>\n\n\n\n<p>En tant qu&rsquo;artiste de graffiti et professionnel de l&rsquo;environnement, Luc jette un pont entre l&rsquo;art et la science, s&rsquo;effor\u00e7ant de d\u00e9couvrir la peinture en a\u00e9rosol la plus durable au monde. Engag\u00e9 \u00e0 d\u00e9velopper son mouvement populaire et \u00e0 favoriser la collaboration entre les industries, Luc utilise la recherche, la narration et les partenariats pour inspirer le changement et montrer comment la durabilit\u00e9 peut transformer les industries pour un avenir plus vert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luc est un sp\u00e9cialiste et un d\u00e9fenseur de l&rsquo;environnement passionn\u00e9 par le d\u00e9veloppement durable et l&rsquo;expression cr\u00e9ative. Combinant son expertise en mati\u00e8re d&rsquo;analyse du cycle de vie (ACV) et sa profonde compr\u00e9hension du d\u00e9veloppement durable, il applique ces connaissances \u00e0 l&rsquo;industrie des a\u00e9rosols et de la peinture en a\u00e9rosol. En tant que fondateur de l&rsquo;Aerosol [&hellip;]<\/p>\n","protected":false},"featured_media":417262,"template":"","meta":{"_seopress_titles_title":"Global Aerosol Summit |  Luc Hillege, The Aerosol Alliance, Founder &amp; Sustainability Consultant","_seopress_titles_desc":"Luc est un sp\u00e9cialiste et un d\u00e9fenseur de l&#039;environnement passionn\u00e9 par le d\u00e9veloppement durable et l&#039;expression cr\u00e9ative. Combinant son expertise en mati\u00e8re d&#039;analyse du cycle de vie (ACV) et sa profonde compr\u00e9hension du d\u00e9veloppement durable, il applique ces connaissances \u00e0 l&#039;industrie des a\u00e9rosols et de la peinture en a\u00e9rosol. En tant que fondateur de l&#039;Aerosol Alliance, Luc travaille avec des artistes, des conservateurs, des fabricants et des recycleurs pour sensibiliser le public et trouver des solutions durables.\r\n\r\nEn tant qu&#039;artiste de graffiti et professionnel de l&#039;environnement, Luc jette un pont entre l&#039;art et la science, s&#039;effor\u00e7ant de d\u00e9couvrir la peinture en a\u00e9rosol la plus durable au monde. Engag\u00e9 \u00e0 d\u00e9velopper son mouvement populaire et \u00e0 favoriser la collaboration entre les industries, Luc utilise la recherche, la narration et les partenariats pour inspirer le changement et montrer comment la durabilit\u00e9 peut transformer les industries pour un avenir plus vert.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"Global Aerosol Summit |  Luc Hillege, The Aerosol Alliance, Founder &amp; Sustainability Consultant","_seopress_social_fb_desc":"","_seopress_social_fb_img":"https:\/\/easyfairsassets.com\/sites\/61\/2024\/12\/Luc-Hillege.png","_seopress_social_fb_img_attachment_id":417262,"_seopress_social_fb_img_width":500,"_seopress_social_fb_img_height":500,"_seopress_social_twitter_title":"Global Aerosol Summit |  Luc Hillege, The Aerosol Alliance, Founder &amp; Sustainability Consultant","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"https:\/\/easyfairsassets.com\/sites\/61\/2024\/12\/Luc-Hillege.png","_seopress_social_twitter_img_attachment_id":417262,"_seopress_social_twitter_img_width":500,"_seopress_social_twitter_img_height":500,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_company_name":"The Aerosol Alliance","_job_title":"Founder & Sustainability Consultant","_visit_me":"","_email":"","_linkedin":"","_twitter":"","_facebook":"","_instagram":"","_youtube":"","_imdb":"","footnotes":""},"edition":[924],"guest_type":[923],"work":[],"class_list":["post-417255","guest","type-guest","status-publish","has-post-thumbnail","hentry","edition-paris-packaging-week-2025","guest_type-global-aerosol-dispensing-summit-2025"],"_cover_image":null,"_links":{"self":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/417255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest"}],"about":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/types\/guest"}],"version-history":[{"count":0,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/417255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media\/417262"}],"wp:attachment":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media?parent=417255"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/edition?post=417255"},{"taxonomy":"guest_type","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest_type?post=417255"},{"taxonomy":"work","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/work?post=417255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}