{"id":82631,"date":"2022-05-23T19:40:46","date_gmt":"2022-05-23T17:40:46","guid":{"rendered":"https:\/\/www.parispackagingweek.com\/?post_type=guest&#038;p=82631"},"modified":"2022-10-31T12:57:21","modified_gmt":"2022-10-31T11:57:21","slug":"vary-cheam-levidence","status":"publish","type":"guest","link":"https:\/\/www.parispackagingweek.com\/fr\/speaker\/vary-cheam-levidence\/","title":{"rendered":"Vary Cheam, L&rsquo;Evidence"},"content":{"rendered":"<p><strong>Directrice g\u00e9n\u00e9rale \u2013 Fondatrice de L\u2019EVIDENCE<\/strong><\/p>\n<p>Dans les ann\u00e9es 90, Vary a dirig\u00e9 les activit\u00e9s commerciales France \u00e0 l\u2019agence IBM Healthcare .<br \/>\nPuis en 2004, elle a rejoint le groupe APAVE o\u00f9 elle a accompagn\u00e9 des entreprises et des collectivit\u00e9s dans leur volont\u00e9 de ma\u00eetriser leurs risques techniques, humains et environnementaux, \u00e0 travers des missions : inspection, b\u00e2timent, essais et mesures, formation, conseil. Elle a ainsi contribu\u00e9 \u00e0 am\u00e9liorer la s\u00e9curit\u00e9 des hommes et des biens, \u00e0 pr\u00e9server l&rsquo;environnement et \u00e0 optimiser la performance des organisations.<br \/>\nSuite \u00e0 son exp\u00e9rience r\u00e9ussie dans la ma\u00eetrise des risques et de la conformit\u00e9 r\u00e9glementaire, Vary CHEAM met \u00e0 profit son savoir-faire et son expertise aupr\u00e8s des entreprises : l\u2019intelligence dans le d\u00e9veloppement.<br \/>\nEt s\u2019appuyant sur un vaste r\u00e9seau d\u2019experts et de sachants issus de divers domaines, sa soci\u00e9t\u00e9 L\u2019EVIDENCE apporte un savoir-faire, un savoir-\u00eatre en assistance technique dans les proc\u00e8s, la construction, QHSE, et assure les mises en relation business.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Directrice g\u00e9n\u00e9rale \u2013 Fondatrice de L\u2019EVIDENCE Dans les ann\u00e9es 90, Vary a dirig\u00e9 les activit\u00e9s commerciales France \u00e0 l\u2019agence IBM Healthcare . Puis en 2004, elle a rejoint le groupe APAVE o\u00f9 elle a accompagn\u00e9 des entreprises et des collectivit\u00e9s dans leur volont\u00e9 de ma\u00eetriser leurs risques techniques, humains et environnementaux, \u00e0 travers des missions [&hellip;]<\/p>\n","protected":false},"featured_media":86703,"template":"","meta":{"_seopress_titles_title":"Vary Cheam | PLD Talks","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_company_name":"","_job_title":"","_visit_me":"","_email":"","_linkedin":"","_twitter":"","_facebook":"","_instagram":"","_youtube":"","_imdb":"","footnotes":""},"edition":[586],"guest_type":[],"work":[],"class_list":["post-82631","guest","type-guest","status-publish","has-post-thumbnail","hentry","edition-paris-packaging-week-speakers-2022"],"_cover_image":null,"_links":{"self":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/82631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest"}],"about":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/types\/guest"}],"version-history":[{"count":0,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest\/82631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media\/86703"}],"wp:attachment":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media?parent=82631"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/edition?post=82631"},{"taxonomy":"guest_type","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/guest_type?post=82631"},{"taxonomy":"work","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/work?post=82631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}