{"id":407957,"date":"2024-11-16T13:44:50","date_gmt":"2024-11-16T12:44:50","guid":{"rendered":"https:\/\/www.parispackagingweek.com\/?p=407957"},"modified":"2024-11-25T16:14:18","modified_gmt":"2024-11-25T15:14:18","slug":"communique-de-presse-lemballage-permet-vraiment-davoir-un-impact-concret-teresa-vargas-matos","status":"publish","type":"post","link":"https:\/\/www.parispackagingweek.com\/fr\/2024\/11\/16\/communique-de-presse-lemballage-permet-vraiment-davoir-un-impact-concret-teresa-vargas-matos\/","title":{"rendered":"Interview | \u00ab L\u2019emballage permet vraiment d\u2019avoir un impact concret \u00bb, Teresa Vargas Matos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"407957\" class=\"elementor elementor-407957\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c04a20a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c04a20a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-35239d0\" data-id=\"35239d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6b5024\" data-id=\"d6b5024\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6ad1b elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3a6ad1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Interview | \u00ab L\u2019emballage permet vraiment d\u2019avoir un impact concret \u00bb, Teresa Vargas Matos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dfaf9c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4dfaf9c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6d940a7\" data-id=\"6d940a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9956d49\" data-id=\"9956d49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee9acd9 elementor-widget elementor-widget-post-info\" data-id=\"ee9acd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-bdf8f56\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2024\/11\/16\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>novembre 16, 2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e66d97 elementor-widget elementor-widget-text-editor\" data-id=\"3e66d97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Teresa Vargas Matos, Co-Fondatrice et Responsable de la Strat\u00e9gie au sein de l\u2019agence de branding et de conseil en transition durable Matters To You Studio, fait partie de la promotion 2025 des Future Leaders identifi\u00e9s Paris Packaging Week. Elle a confi\u00e9 \u00e0 Premium Beauty News sa vision du monde de l\u2019emballage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31fd917 elementor-widget elementor-widget-text-editor\" data-id=\"31fd917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Pouvez-vous vous pr\u00e9senter, ainsi que votre r\u00f4le et votre exp\u00e9rience dans l\u2019industrie de l\u2019emballage\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe36ee elementor-widget elementor-widget-text-editor\" data-id=\"bfe36ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0Je m\u2019appelle Teresa, et je suis co-fondatrice et responsable de la strat\u00e9gie chez\u00a0<strong><a class=\"spip_out\" href=\"https:\/\/matterstoyoustudio.com\/\" target=\"_blank\" rel=\"noopener noreferrer external\">Matters To You Studio<\/a><\/strong>. Pour vous donner un peu de contexte, j\u2019ai commenc\u00e9 par des \u00e9tudes en Luxury Brand Management \u00e0 l\u2019INSEEC de Bordeaux. Ensuite, j\u2019ai eu l\u2019opportunit\u00e9 de me plonger dans l\u2019univers des cosm\u00e9tiques et de l\u2019emballage \u00e9coresponsable, en travaillant chez Est\u00e9e Lauder et WISTADTS. Avec le temps, j\u2019ai r\u00e9alis\u00e9 \u00e0 quel point le domaine de l\u2019emballage est passionnant, parce qu\u2019il ne se limite pas \u00e0 l\u2019innovation\u00a0: il permet vraiment d\u2019avoir un impact concret. Aujourd\u2019hui, apr\u00e8s plus de huit ans dans l\u2019industrie, mon objectif est d\u2019accompagner les marques dans leur transition vers des solutions durables pour l\u2019avenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c4e693 elementor-widget elementor-widget-text-editor\" data-id=\"1c4e693\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Qu\u2019est-ce qui vous a inspir\u00e9 \u00e0 poursuivre une carri\u00e8re dans l\u2019industrie de l\u2019emballage\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c25dd18 elementor-widget elementor-widget-text-editor\" data-id=\"c25dd18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0Honn\u00eatement, tout s\u2019est fait un peu par hasard. J\u2019avais choisi de me sp\u00e9cialiser dans l\u2019industrie des cosm\u00e9tiques dans le cadre de mes \u00e9tudes en\u00a0<i>Luxury Brand Management<\/i>\u00a0\u00e0 Bordeaux, ce qui impliquait aussi de faire des recherches sur ce secteur. Quand j\u2019ai commenc\u00e9 \u00e0 travailler, l\u2019emballage est rapidement devenu un domaine cl\u00e9, et j\u2019ai eu la chance de participer \u00e0 un projet de design d\u2019emballage innovant en mono-mat\u00e9riau, o\u00f9 la durabilit\u00e9 \u00e9tait au c\u0153ur des pr\u00e9occupations. J\u2019ai tout de suite accroch\u00e9. J\u2019ai toujours \u00e9t\u00e9 attir\u00e9e par le branding et l\u2019esth\u00e9tique, et avec l\u2019emballage, j\u2019ai d\u00e9couvert une mani\u00e8re de cr\u00e9er un v\u00e9ritable impact. Aujourd\u2019hui, j\u2019ai l\u2019impression de faire quelque chose qui a un sens, quelque chose qui peut vraiment faire la diff\u00e9rence.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f52622d elementor-widget elementor-widget-text-editor\" data-id=\"f52622d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Quel est l\u2019un des plus grands d\u00e9fis que vous avez rencontr\u00e9s en tant que jeune leader dans l\u2019industrie de l\u2019emballage\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37c641a elementor-widget elementor-widget-text-editor\" data-id=\"37c641a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0Le sujet des syst\u00e8mes de recyclage, sans h\u00e9sitation. Ils sont tellement diff\u00e9rents d\u2019une r\u00e9gion \u00e0 l\u2019autre, d\u2019un pays \u00e0 l\u2019autre, et il n\u2019existe pas de normes universelles. R\u00e9sultat\u00a0: c\u2019est la confusion totale, aussi bien pour les consommateurs que pour les marques, ce qui complique \u00e9norm\u00e9ment la conception d\u2019emballages recyclables partout. L\u2019industrie n\u2019a pas encore trouv\u00e9 de solutions claires qui conviennent \u00e0 tous les mat\u00e9riaux ni de processus de recyclage vraiment optimaux. Face \u00e0 ce d\u00e9fi, je pense qu\u2019il est indispensable de d\u00e9passer la simple id\u00e9e de recyclabilit\u00e9 et d\u2019int\u00e9grer des notions comme la consommation responsable, la r\u00e9duction et la r\u00e9utilisation. La durabilit\u00e9 est un concept large, donc trouver une solution miracle, c\u2019est compliqu\u00e9. C\u2019est pour \u00e7a qu\u2019il ne faut pas seulement am\u00e9liorer les syst\u00e8mes de recyclage, mais aussi guider l\u2019industrie vers des pratiques plus circulaires et responsables, qui limitent la consommation de ressources, r\u00e9duisent les d\u00e9chets, et donnent aux produits plusieurs vies.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cc8e97 elementor-widget elementor-widget-text-editor\" data-id=\"2cc8e97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Si vous pouviez changer une chose dans l\u2019industrie de l\u2019emballage, que serait-ce et pourquoi\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd81827 elementor-widget elementor-widget-text-editor\" data-id=\"dd81827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0Je dirais qu\u2019il y a un vrai manque de connaissances sur les pratiques durables. Beaucoup de marques ne disposent pas de l\u2019expertise ou des ressources n\u00e9cessaires pour mettre en place des strat\u00e9gies de durabilit\u00e9 qui tiennent la route. Du coup, elles prennent souvent des initiatives un peu improvis\u00e9es pour rendre leurs emballages plus \u00e9cologiques. \u00c0 mon avis, investir dans des conseils sp\u00e9cialis\u00e9s devrait \u00eatre une priorit\u00e9, pour aider les marques \u00e0 suivre une direction plus r\u00e9fl\u00e9chie. La transition vers des solutions durables ne peut vraiment marcher que si les marques voient la durabilit\u00e9 comme un \u00e9l\u00e9ment central de leur business, et pas juste comme une contrainte impos\u00e9e par le march\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8cb8be elementor-widget elementor-widget-text-editor\" data-id=\"a8cb8be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Comment voyez-vous le r\u00f4le des futurs leaders comme vous dans l\u2019\u00e9volution de l\u2019industrie\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ffdacd elementor-widget elementor-widget-text-editor\" data-id=\"8ffdacd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0Je pense que notre g\u00e9n\u00e9ration repr\u00e9sente les nouvelles attentes des consommateurs et apporte une affinit\u00e9 naturelle pour les outils num\u00e9riques et les technologies innovantes qui peuvent vraiment transformer la conception et la production des emballages. On ne se limite pas \u00e0 la durabilit\u00e9\u00a0: on veut aussi innover et cr\u00e9er des interactions transparentes avec les consommateurs. Pour nous, il est essentiel de garantir des pratiques durables authentiques et d\u2019\u00e9viter le greenwashing.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da4da7c elementor-widget elementor-widget-text-editor\" data-id=\"da4da7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Quel conseil donneriez-vous aux jeunes professionnels qui d\u00e9butent dans l\u2019industrie de l\u2019emballage\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cf15dc elementor-widget elementor-widget-text-editor\" data-id=\"0cf15dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0Je leur dirais de rester curieux et de continuer \u00e0 apprendre et \u00e0 s\u2019adapter. L\u2019industrie de l\u2019emballage \u00e9volue rapidement avec l\u2019arriv\u00e9e de nouveaux mat\u00e9riaux, designs et technologies, souvent influenc\u00e9s par les pr\u00e9f\u00e9rences des consommateurs et les r\u00e9glementations sur la durabilit\u00e9. Il est important d\u2019int\u00e9grer la durabilit\u00e9 dans leur apprentissage et de rester flexibles et r\u00e9silients pour pouvoir contribuer aux \u00e9volutions futures du secteur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e01035b elementor-widget elementor-widget-text-editor\" data-id=\"e01035b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Qu\u2019est-ce que cela signifie pour vous d\u2019avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour rejoindre le programme \u00ab\u00a0Future Leaders\u00a0\u00bb\u00a0?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-882284e elementor-widget elementor-widget-text-editor\" data-id=\"882284e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teresa Vargas Matos &#8211;<\/strong>\u00a0\u00catre\u00a0<a class=\"spip_out\" href=\"https:\/\/register.visitcloud.com\/survey\/1690vq5t1wlpc?actioncode=202&amp;gad_source=1&amp;gclid=Cj0KCQiAoae5BhCNARIsADVLzZcp7Tw2RqmFleyKJFWKw3C3Kb6qXO-M99lf-2ONc1H9YPF9O84TNroaAhkCEALw_wcB\" target=\"_blank\" rel=\"noopener noreferrer external\">choisie comme Future Leader<\/a>, c\u2019est vraiment un honneur et un immense pas en avant qui reconna\u00eet tout le travail que j\u2019ai accompli pour promouvoir des changements positifs dans l\u2019industrie ces derni\u00e8res ann\u00e9es. Cela vient aussi avec une responsabilit\u00e9\u00a0: utiliser mes comp\u00e9tences, mes id\u00e9es et mon leadership pour relever les d\u00e9fis majeurs du secteur. Et puis, c\u2019est une super opportunit\u00e9 d\u2019apprendre directement aupr\u00e8s des leaders d\u2019aujourd\u2019hui.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a13995f elementor-widget elementor-widget-text-editor\" data-id=\"a13995f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour en apprendre davantage sur Teresa et les autres\u00a0<a href=\"https:\/\/www.premiumbeautynews.com\/fr\/paris-packaging-week-devoile-une,24735\">\u00ab\u00a0Future Leaders\u00a0\u00bb<\/a>, rendez-vous \u00e0 la\u00a0<a href=\"https:\/\/www.premiumbeautynews.com\/fr\/la-paris-packaging-week-revient-en,24618\">Paris Packaging Week qui aura lieu les 28 et 29 janvier 2025<\/a>\u00a0\u00e0 Paris Expo Portes de Versailles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3921674 elementor-widget elementor-widget-text-editor\" data-id=\"3921674\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00c0 propos d&rsquo;Easyfairs <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad2395 elementor-widget elementor-widget-text-editor\" data-id=\"3ad2395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Easyfairs organise et accueille des \u00e9v\u00e9nements visant \u00e0 rassembler des communaut\u00e9s et \u00e0 leur offrir une <strong>vision de l&rsquo;avenir<\/strong>.<\/p><p>Le groupe organise actuellement 110 titres d&rsquo;\u00e9v\u00e9nements leader sur le march\u00e9 dans 12\u00a0pays (Alg\u00e9rie, Belgique, Finlande, France, Allemagne, Italie, Pays-Bas, Portugal, Espagne, Su\u00e8de, Suisse et Royaume-Uni) et g\u00e8re huit halls d&rsquo;exposition en Belgique, aux Pays-Bas et en Su\u00e8de (Anvers, Gand, Malines-Bruxelles Nord, Namur, Gorinchem, Hardenberg, Malm\u00f6 et Stockholm).<\/p><p>Chez Easyfairs, nous sommes anim\u00e9s par la volont\u00e9 de faciliter la vie de nos clients, d&rsquo;augmenter le retour sur investissement et d&rsquo;optimiser leur temps gr\u00e2ce \u00e0 des formules \u00ab\u00a0all inclusive\u00a0\u00bb, une technologie avanc\u00e9e et une approche centr\u00e9e sur le client. Nos produits et outils digitaux offrent \u00e0 nos communaut\u00e9s d&rsquo;excellentes occasions de nouer des contacts efficaces et de faire des affaires tout au long de l&rsquo;ann\u00e9e.<\/p><p>Le groupe Easyfairs emploie 820\u00a0talents tr\u00e8s engag\u00e9s, d\u00e9ploie les meilleurs outils marketing et technologiques et d\u00e9veloppe des marques attrayantes et pertinentes pour ses communaut\u00e9s.<\/p><p>En 2024, Easyfairs s&rsquo;est vu d\u00e9cerner le titre de \u00ab\u00a0Best Managed Company\u00a0\u00bb par Deloitte pour la sixi\u00e8me ann\u00e9e cons\u00e9cutive.<\/p><p>Par ailleurs, Easyfairs est fi\u00e8re de figurer parmi les 20 premiers organisateurs de salons au monde, selon le classement annuel STAX.<\/p><p><em>Visit the future<\/em> avec Easyfairs et d\u00e9couvrez-en davantage sur <a href=\"http:\/\/www.easyfairs.com\">www.easyfairs.com<\/a>.<\/p><p><strong>Pour en savoir plus, veuillez contacter\u00a0:<\/strong><\/p><p>Noura Moussa &#8211; Relations Presse<\/p><p>noura.moussa@henaray.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3083f elementor-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-dynamic-button\" data-id=\"6d3083f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"dynamic-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-button-wrapper\">\n            <a href=\"https:\/\/www.instagram.com\/vogis.gin\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm elementor-animation-grow\" role=\"button\">\n                        <span class=\"elementor-button-content-wrapper\">\n\t\t\t                <span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t<\/span>\n            \t\t\t<span class=\"elementor-button-text\"><\/span>\n\t\t<\/span>\n                    <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6e140 elementor-align-justify elementor-widget elementor-widget-dynamic-button\" data-id=\"8b6e140\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"dynamic-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-button-wrapper\">\n            <a href=\"https:\/\/register.visitcloud.com\/survey\/1690vq5t1wlpc\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm elementor-animation-grow\" role=\"button\">\n                        <span class=\"elementor-button-content-wrapper\">\n\t\t\t                <span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n            \t\t\t<span class=\"elementor-button-text\">INSCRIVEZ-VOUS ICI<\/span>\n\t\t<\/span>\n                    <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efee721 elementor-icon-list--layout-inline elementor-align-center elementor-tablet-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"efee721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/parispackagingweek\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/parispackweek\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/showcase\/parispackagingweek\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/parispackagingweek\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-403ea04 elementor-widget elementor-widget-heading\" data-id=\"403ea04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partager cet article<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52c65bf elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"52c65bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Share on twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8f6aa53\" data-id=\"8f6aa53\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e19583 elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-desktop elementor-widget elementor-widget-wp-widget-adsanity-single\" data-id=\"2e19583\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:140,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset_tablet&quot;:150,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"wp-widget-adsanity-single.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"ad-65633\" class=\"ad-426x249 adsanity-426x249  adsanity-\"\n><div class=\"adsanity-inner\">\n\n<div class=\"adsanity-gati\" data-title=\"Horizontal example\"><a rel=\"nofollow\" href=\"https:\/\/www.parispackagingweek.com\/fr\/ads\/horizontal-example\/\"  target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" width=\"426\" height=\"249\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2022\/04\/426-x-249_Yoga.jpg\" class=\"no-lazy-load wp-post-image\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2022\/04\/426-x-249_Yoga.jpg 426w, https:\/\/easyfairsassets.com\/sites\/61\/2022\/04\/426-x-249_Yoga-300x175.jpg 300w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/><\/a><\/div>\n<\/div><\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-860a842 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"860a842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"696\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2024\/11\/Teresa-Vargas-Matos-1200-x-696-3.png\" class=\"attachment-full size-full wp-image-408002\" alt=\"Teresa Vargas Matos 1200 x 696\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2024\/11\/Teresa-Vargas-Matos-1200-x-696-3.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2024\/11\/Teresa-Vargas-Matos-1200-x-696-3-300x174.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2024\/11\/Teresa-Vargas-Matos-1200-x-696-3-768x445.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecb3eaa elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"ecb3eaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Photo de <a href=\"https:\/\/www.securikett.com\/sustainable-security-solutions\/\">Securikett<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa2e5ad elementor-widget elementor-widget-spacer\" data-id=\"aa2e5ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-654365c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"654365c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b8ed3c8\" data-id=\"b8ed3c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b76adf elementor-widget elementor-widget-heading\" data-id=\"5b76adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abonnez-vous \u00e0 la newsletter du salon<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c64cc38 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"c64cc38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Fruit Newsletters\" aria-label=\"Fruit Newsletters\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"407957\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c64cc38\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-Email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[Email]\" id=\"form-field-Email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Adresse email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_1e34227 elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_1e34227\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcRLiMdAAAAAMfz2VLOztX3J4YGX2zjQnrCNW2V\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm elementor-animation-grow\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-45d6bbf elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"45d6bbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a188940 elementor-widget elementor-widget-heading\" data-id=\"a188940\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les derniers articles de Paris Packaging Week<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-607271b elementor-posts--align-left elementor-grid-2 elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"607271b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;49&quot;,&quot;sizes&quot;:[]},&quot;classic_columns&quot;:&quot;2&quot;,&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-505305 post type-post status-publish format-standard has-post-thumbnail hentry category-beauty-en category-design-en category-luxury-en category-trends-en\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/26\/hermes-devoile-un-packaging-en-edition-limitee-pour-ses-rouges-a-levres-automne-hiver-2026\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Hermes-Lipstick.png\" class=\"attachment-full size-full wp-image-505306\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Hermes-Lipstick.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Hermes-Lipstick-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Hermes-Lipstick-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/26\/hermes-devoile-un-packaging-en-edition-limitee-pour-ses-rouges-a-levres-automne-hiver-2026\/\" >\n\t\t\t\tHerm\u00e8s d\u00e9voile un packaging en \u00e9dition limit\u00e9e pour ses rouges \u00e0 l\u00e8vres Automne-Hiver 2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504611 post type-post status-publish format-standard has-post-thumbnail hentry category-aerosols-dispensing-2 category-aerosols-dispensing-3 category-business-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/18\/unilever-accelere-la-transformation-de-ses-usines-grace-a-lia\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Unilever-AI.png\" class=\"attachment-full size-full wp-image-504614\" alt=\"Paris Packaging Week | Unilever takes factory management into the digital age with AI\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Unilever-AI.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Unilever-AI-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Unilever-AI-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/18\/unilever-accelere-la-transformation-de-ses-usines-grace-a-lia\/\" >\n\t\t\t\tUnilever acc\u00e9l\u00e8re la transformation de ses usines gr\u00e2ce \u00e0 l\u2019IA\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504559 post type-post status-publish format-standard has-post-thumbnail hentry category-design-2 category-innovation-2 category-trends-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/18\/exclusif-glowa-le-skincare-pense-pour-vous-suivre-partout\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/GLOWA-1.png\" class=\"attachment-full size-full wp-image-504562\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/GLOWA-1.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/GLOWA-1-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/GLOWA-1-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/18\/exclusif-glowa-le-skincare-pense-pour-vous-suivre-partout\/\" >\n\t\t\t\tExclusif | GLOWA : le skincare pens\u00e9 pour vous suivre partout\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504531 post type-post status-publish format-standard has-post-thumbnail hentry category-beauty category-innovation-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/18\/innovation-awards-spotlight-jil-sander\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/JIL-sander.png\" class=\"attachment-full size-full wp-image-504534\" alt=\"Innovation Awards spotlight | Jil Sander\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/JIL-sander.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/JIL-sander-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/JIL-sander-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/18\/innovation-awards-spotlight-jil-sander\/\" >\n\t\t\t\tInnovation Awards spotlight | Jil Sander\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504275 post type-post status-publish format-standard has-post-thumbnail hentry category-design-2 category-drinks category-trends-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/17\/7up-met-le-citron-vert-a-lhonneur-avec-une-nouvelle-identite-visuelle\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/7UP.png\" class=\"attachment-full size-full wp-image-504277\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/7UP.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/7UP-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/7UP-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/17\/7up-met-le-citron-vert-a-lhonneur-avec-une-nouvelle-identite-visuelle\/\" >\n\t\t\t\t7UP met le citron vert \u00e0 l&rsquo;honneur avec une nouvelle identit\u00e9 visuelle\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504253 post type-post status-publish format-standard has-post-thumbnail hentry category-design-2 category-drinks category-trends-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/14\/breizh-cola-accelere-sa-strategie-packaging-avec-la-canette\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Breizh-Cola.png\" class=\"attachment-full size-full wp-image-504255\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Breizh-Cola.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Breizh-Cola-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Breizh-Cola-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/14\/breizh-cola-accelere-sa-strategie-packaging-avec-la-canette\/\" >\n\t\t\t\tBreizh Cola acc\u00e9l\u00e8re sa strat\u00e9gie packaging avec la canette\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504096 post type-post status-publish format-standard has-post-thumbnail hentry category-design-2 category-drinks category-trends-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/14\/un-verre-pense-pour-equilibre-lhydratation\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Beer-Glass.png\" class=\"attachment-full size-full wp-image-504081\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Beer-Glass.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Beer-Glass-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Beer-Glass-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/14\/un-verre-pense-pour-equilibre-lhydratation\/\" >\n\t\t\t\tUn verre pens\u00e9 pour \u00e9quilibrer l&rsquo;hydratation\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-504210 post type-post status-publish format-standard has-post-thumbnail hentry category-design-2 category-drinks category-trends-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/14\/waterloo-rafraichit-son-packaging\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"626\" src=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Waterloo.png\" class=\"attachment-full size-full wp-image-504226\" alt=\"\" srcset=\"https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Waterloo.png 1200w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Waterloo-300x157.png 300w, https:\/\/easyfairsassets.com\/sites\/61\/2026\/08\/Waterloo-768x401.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.parispackagingweek.com\/fr\/2026\/08\/14\/waterloo-rafraichit-son-packaging\/\" >\n\t\t\t\tWaterloo rafra\u00eechit son packaging\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60377b9 elementor-align-justify elementor-widget elementor-widget-dynamic-button\" data-id=\"60377b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"dynamic-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-button-wrapper\">\n            <a href=\"https:\/\/www.parispackagingweek.com\/fr\/newsletter\/\" class=\"elementor-button-link elementor-button elementor-size-sm elementor-animation-grow\" role=\"button\">\n                        <span class=\"elementor-button-content-wrapper\">\n\t\t\t                <span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n            \t\t\t<span class=\"elementor-button-text\">Inscrivez-vous \u00e0 la newsletter<\/span>\n\t\t<\/span>\n                    <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5e0c966\" data-id=\"5e0c966\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Teresa Vargas Matos, Co-Fondatrice et Responsable de la Strat\u00e9gie au sein de l\u2019agence de branding et de conseil en<\/p>\n","protected":false},"author":85,"featured_media":408002,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Paris Packaging Week | Interview | \u00ab L\u2019emballage permet vraiment d\u2019avoir un impact concret \u00bb, Teresa Vargas Matos","_seopress_titles_desc":"Teresa Vargas Matos, Co-Fondatrice et Responsable de la Strat\u00e9gie au sein de l\u2019agence de branding et de conseil en transition durable Matters To You Studio, fait partie de la promotion 2025 des Future Leaders identifi\u00e9s Paris Packaging Week. Elle a confi\u00e9 \u00e0 Premium Beauty News sa vision du monde de l\u2019emballage.\r\n","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"Paris Packaging Week | Interview | \u00ab L\u2019emballage permet vraiment d\u2019avoir un impact concret \u00bb, Teresa Vargas Matos","_seopress_social_fb_desc":"Teresa Vargas Matos, Co-Fondatrice et Responsable de la Strat\u00e9gie au sein de l\u2019agence de branding et de conseil en transition durable Matters To You Studio, fait partie de la promotion 2025 des Future Leaders identifi\u00e9s Paris Packaging Week. Elle a confi\u00e9 \u00e0 Premium Beauty News sa vision du monde de l\u2019emballage.","_seopress_social_fb_img":"https:\/\/easyfairsassets.com\/sites\/61\/2024\/11\/Teresa-Vargas-Matos-1200-x-696-3.png","_seopress_social_fb_img_attachment_id":408002,"_seopress_social_fb_img_width":1200,"_seopress_social_fb_img_height":696,"_seopress_social_twitter_title":"Paris Packaging Week | Interview | \u00ab L\u2019emballage permet vraiment d\u2019avoir un impact concret \u00bb, Teresa Vargas Matos","_seopress_social_twitter_desc":"Teresa Vargas Matos, Co-Fondatrice et Responsable de la Strat\u00e9gie au sein de l\u2019agence de branding et de conseil en transition durable Matters To You Studio, fait partie de la promotion 2025 des Future Leaders identifi\u00e9s Paris Packaging Week. Elle a confi\u00e9 \u00e0 Premium Beauty News sa vision du monde de l\u2019emballage.","_seopress_social_twitter_img":"https:\/\/easyfairsassets.com\/sites\/61\/2024\/11\/Teresa-Vargas-Matos-1200-x-696-3.png","_seopress_social_twitter_img_attachment_id":408002,"_seopress_social_twitter_img_width":1200,"_seopress_social_twitter_img_height":696,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[{"url":"","title":"","desc":"","thumbnail":"","duration":"","rating":"","view_count":"","tag":""}],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[119,121,117,120,118,116],"tags":[],"edition":[],"class_list":["post-407957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-2","category-design-2","category-event-news-2","category-innovation-2","category-sustainability-2","category-trends-2"],"_links":{"self":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/posts\/407957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/comments?post=407957"}],"version-history":[{"count":0,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/posts\/407957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media\/408002"}],"wp:attachment":[{"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/media?parent=407957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/categories?post=407957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/tags?post=407957"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.parispackagingweek.com\/fr\/wp-json\/wp\/v2\/edition?post=407957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}